{"id":112181,"date":"2022-11-23T09:58:56","date_gmt":"2022-11-23T12:58:56","guid":{"rendered":"https:\/\/www.rieles.com\/front\/?p=112181"},"modified":"2022-11-23T09:58:57","modified_gmt":"2022-11-23T12:58:57","slug":"productores-rurales-visitaron-puerto-quequen-y-pidieron-por-el-regreso-del-tren-de-cargas","status":"publish","type":"post","link":"https:\/\/www.rieles.com\/front\/productores-rurales-visitaron-puerto-quequen-y-pidieron-por-el-regreso-del-tren-de-cargas\/","title":{"rendered":"Productores rurales visitaron Puerto Quequ\u00e9n y pidieron por el regreso del tren de cargas"},"content":{"rendered":"\n<p style=\"text-align: justify;\"><strong>Buenos Aires &#8211; Argentina &#8211; 23\/11\/2022: <\/strong>Durante un importante encuentro celebrado en la ciudad de Necochea, miembros de la Confederaci\u00f3n de Asociaciones Rurales de Buenos Aires y La Pampa (CARBAP) visitaron Puerto Quequ\u00e9n y concidieron en la importancia de recuperar el tren de cargas.<br>La Sociedad Rural del distrito fue sede, el viernes pasado, de la reuni\u00f3n encabezada por Horacio Salaverri, mientras que como anfitriones actuaron Patricio Bosch, Eugenio Cardenau y Juan Pablo Escand\u00f3n.<br>La amplia asistencia qued\u00f3 puesta de manifiesto por la presencia de delegaciones de los partidos de Benito Ju\u00e1rez, Rauch, Lober\u00eda, Adolfo Gonz\u00e1lez Ch\u00e1ves, General Guido, Tandil, San Cayetano, Balcarce, Mar Chiquita, y General Pueyrred\u00f3n.<br>En cuanto al temario abordado, pudo saberse que una de las cuestiones gir\u00f3 en torno a la dif\u00edcil situaci\u00f3n de los productores agropecuarios por la falta de lluvias y las heladas, su impacto negativo en las distintas producciones y los paliativos que podr\u00eda otorgar el gobierno.<br>Los ruralistas visitaron el Consorcio de Gesti\u00f3n de Puerto Quequ\u00e9n y las distintas terminales de esa estaci\u00f3n mar\u00edtima bonaerense.<br>En tal sentido, sobresali\u00f3 la inquietud de las entidades en lograr captar m\u00e1s cargas hacia ese puerto y la necesidad de recuperar el servicio ferroviario de cargas.<br>Seg\u00fan el medio El F\u00e9nix Digital, de Benito Ju\u00e1rez, el dirigente Pablo Go\u00f1i el tema fue analizado con las autoridades del ente portuario, ya que desde hace tiempo las entidades ruralistas del Sudeste vienen trabajando para el retorno de los trenes.<br>\u201cEste tema est\u00e1 puesto en la agenda de CARBAP, lo trabajamos con las dem\u00e1s entidades\u00bb<br>Tambi\u00e9n se\u00f1al\u00f3 que pudieron recorrer el puerto, el Sitio Cero y apreciar todas las posibilidades que tiene Quequ\u00e9n como puerto de calado profundo, importante para seguir con las distintas exportaciones y agregar incluso el transporte de contenedores.<br>Cabe recordar que el regreso del tren de cargas fue abordado d\u00edas atr\u00e1s por intendentes y funcionarios de Tandil, Lober\u00eda, Rauch, General Alvarado, Balcarce, Ayacucho, Necochea y San Cayetano, entre otros, quienes se reunieron con el fin de intentar terminar con esa limitaci\u00f3n log\u00edstica.<br>\u00abDesde hace tiempo, este grupo de distritos viene trabajando en la elaboraci\u00f3n de un proyecto de desarrollo regional, en el que el tren de cargas al puerto de Quequ\u00e9n es uno de los temas principales\u00bb, dijo el municipio de Tandil, a trav\u00e9s de un comunicado.<\/p>\n\n\n\n<p class=\"has-vivid-red-color has-text-color wp-block-paragraph\">Fuente: <strong><a href=\"https:\/\/www.sudoesteba.com\/2022-11-22\/productores-rurales-visitaron-puerto-quequen-y-pidieron-por-el-regreso-del-tren-de-cargas-4425\/\" data-type=\"URL\" data-id=\"https:\/\/www.sudoesteba.com\/2022-11-22\/productores-rurales-visitaron-puerto-quequen-y-pidieron-por-el-regreso-del-tren-de-cargas-4425\/\" target=\"_blank\" rel=\"noreferrer noopener\">Sudoeste BA<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buenos Aires &#8211; Argentina &#8211; 23\/11\/2022: Durante un importante encuentro celebrado en la ciudad de Necochea, miembros de la Confederaci\u00f3n de Asociaciones Rurales de Buenos Aires y La Pampa (CARBAP) visitaron Puerto Quequ\u00e9n y concidieron en la importancia de recuperar el tren de cargas.La Sociedad Rural del distrito fue sede, el viernes pasado, de la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":112154,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[10855,9105,9644],"class_list":["post-112181","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacionales","tag-10855","tag-actualidad","tag-news"],"_links":{"self":[{"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/posts\/112181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/comments?post=112181"}],"version-history":[{"count":1,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/posts\/112181\/revisions"}],"predecessor-version":[{"id":112182,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/posts\/112181\/revisions\/112182"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/media\/112154"}],"wp:attachment":[{"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/media?parent=112181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/categories?post=112181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/tags?post=112181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}