{"id":115159,"date":"2023-05-12T10:59:04","date_gmt":"2023-05-12T13:59:04","guid":{"rendered":"https:\/\/www.rieles.com\/front\/?p=115159"},"modified":"2023-05-12T10:59:04","modified_gmt":"2023-05-12T13:59:04","slug":"pais-vasco-el-museo-vasco-del-ferrocarril-de-euskotren-pondra-en-circulacion-tres-trenes-de-vapor-el-proximo-fin-de-semana-2","status":"publish","type":"post","link":"https:\/\/www.rieles.com\/front\/pais-vasco-el-museo-vasco-del-ferrocarril-de-euskotren-pondra-en-circulacion-tres-trenes-de-vapor-el-proximo-fin-de-semana-2\/","title":{"rendered":"Pa\u00eds Vasco: El Museo Vasco del Ferrocarril de Euskotren pondr\u00e1 en circulaci\u00f3n tres trenes de vapor el pr\u00f3ximo fin de semana"},"content":{"rendered":"\n<p style=\"text-align: justify;\"><strong>Pa\u00eds Vasco &#8211; 12\/05\/2023: <\/strong>El Museo Vasco del Ferrocarril de Euskotren, Sociedad P\u00fablica del Gobierno Vasco, pondr\u00e1 en circulaci\u00f3n tres trenes de vapor el pr\u00f3ximo fin de semana. Estos servicios se incluyen dentro de la temporada regular, en la que habr\u00e1 salidas de trenes hist\u00f3ricos todos los s\u00e1bados y domingos hasta noviembre.<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code><strong>Los trenes de vapor tendr\u00e1n el siguiente horario de salida desde el Museo (Azpeitia) hacia Lasao:<\/strong><br>\u2022 S\u00e1bado 13 de mayo: 12:00 y 17:30 horas.<br>\u2022 Domingo 14 de mayo: 12:00 horas.<\/code><\/pre>\n\n\n\n<pre class=\"wp-block-code\"><code><strong>El horario de apertura de las instalaciones del Museo es el siguiente:<\/strong><br>\u2022 Martes a viernes: de 10:00 a 13:30 y de 15:00 a 18:30 horas.<br>\u2022 S\u00e1bados: de 10:30 a 14:00 y de 16:00 a 19:30 h.<br>\u2022 Domingos y festivos de 10:30 a 14:00 horas.<\/code><\/pre>\n\n\n\n<p style=\"text-align: justify;\">El Museo Vasco del Ferrocarril expone en sus instalaciones una de las mejores colecciones ferroviarias de Europa, con veh\u00edculos de todo tipo: locomotoras de vapor, di\u00e9sel y el\u00e9ctricas; automotores y diversas clases de vagones.<br>Ofrece, asimismo, uno de los m\u00e1s completos conjuntos de m\u00e1quina-herramienta de Euskadi, a trav\u00e9s del antiguo taller mec\u00e1nico del Ferrocarril del Urola, y cuenta con las muestras de los uniformes utilizados en el ferrocarril desde finales del siglo XIX y de una de las mejores colecciones de relojer\u00eda ferroviaria del mundo.<br><strong>Fogonera\/o por un d\u00eda<\/strong><br>Dentro de las actividades del Museo, se ha recuperado la iniciativa \u2018Fogonera\/o por un d\u00eda\u2019 que consiste en un viaje completo de Ida y Vuelta en la cabina de la locomotora de vapor para poder observar de cerca todos los preparativos precisos para la puesta en marcha de la locomotora. Se recibir\u00e1 la formaci\u00f3n y el equipamiento necesario para garantizar la seguridad en todo momento. Para participar en esta exclusiva experiencia, cuyo precio es de 50 euros, las personas interesadas deben reservar a trav\u00e9s del correo electr\u00f3nico \u2013 museoa@euskotren.eus &#8211; con una antelaci\u00f3n m\u00ednima de 72 horas previas a la jornada elegida.<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code><strong>Informaci\u00f3n al p\u00fablico<\/strong>\n\u2022 Direcci\u00f3n del Museo Vasco del Ferrocarril: calle Juli\u00e1n Elorza, 8 (20730 AZPEITIA-GIPUZKOA).\n\u2022 Tel\u00e9fono de informaci\u00f3n: 943 15 06 77\n\u2022 Fax: 943 15 07 46\n\u2022 Correo electr\u00f3nico: museoa@euskotren.eus\n\u2022 P\u00e1gina web: <a href=\"http:\/\/www.euskotren.eus\" data-type=\"URL\" data-id=\"www.euskotren.eus\" target=\"_blank\" rel=\"noreferrer noopener\">www.euskotren.eus<\/a><\/code><\/pre>\n\n\n\n<p class=\"has-vivid-red-color has-text-color\"><strong>Fuente: Agencia Rieles<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pa\u00eds Vasco &#8211; 12\/05\/2023: El Museo Vasco del Ferrocarril de Euskotren, Sociedad P\u00fablica del Gobierno Vasco, pondr\u00e1 en circulaci\u00f3n tres trenes de vapor el pr\u00f3ximo fin de semana. Estos servicios se incluyen dentro de la temporada regular, en la que habr\u00e1 salidas de trenes hist\u00f3ricos todos los s\u00e1bados y domingos hasta noviembre. El Museo Vasco [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":115148,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13902],"tags":[10855,9105,9644],"class_list":{"0":"post-115159","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-rieles-iberica","8":"tag-10855","9":"tag-actualidad","10":"tag-news"},"_links":{"self":[{"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/posts\/115159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/comments?post=115159"}],"version-history":[{"count":1,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/posts\/115159\/revisions"}],"predecessor-version":[{"id":115160,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/posts\/115159\/revisions\/115160"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/media\/115148"}],"wp:attachment":[{"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/media?parent=115159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/categories?post=115159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/tags?post=115159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}