{"id":35872,"date":"2015-12-18T12:55:51","date_gmt":"2015-12-18T15:55:51","guid":{"rendered":"http:\/\/www.rieles.com\/front\/?p=35872"},"modified":"2015-12-18T12:55:51","modified_gmt":"2015-12-18T15:55:51","slug":"espana-el-primer-tren-de-alta-velocidad-culmina-el-viaje-a-madrid-con-dos-minutos-de-sobra","status":"publish","type":"post","link":"https:\/\/www.rieles.com\/front\/espana-el-primer-tren-de-alta-velocidad-culmina-el-viaje-a-madrid-con-dos-minutos-de-sobra\/","title":{"rendered":"Espa\u00f1a: El primer tren de alta velocidad culmina el viaje a Madrid con dos minutos de sobra"},"content":{"rendered":"<p>El tren Alvia que estren\u00f3 la alta velocidad ferroviaria en Zamora, con el primer servicio comercial que utilizaba la nueva l\u00ednea entre la capital y Olmedo, cubri\u00f3 el recorrido hasta la estaci\u00f3n madrile\u00f1a de Chamart\u00edn sin ning\u00fan tipo de problema, en un c\u00f3modo viaje que lleg\u00f3 incluso con dos minutos sobre el horario previsto.<\/p>\n<p>Fueron 28 los viajeros que tomaron este primer tren, una cifra no demasiado alta aunque hay que tener en cuenta varios factores, como el hecho de que las taquillas para este trayecto estuvieran abiertas apenas 36 horas antes (hasta las siete y media de la tarde del martes no se abri\u00f3 en Internet la venta de tickets) y que se trata de un servicio nuevo, por tanto poco conocido a\u00fan por los usuarios. El convoy que inicio el primer servicio directo entre Zamora y Madrid es un Alvia h\u00edbrido de 264 plazas, el mismo que circula por la l\u00ednea de Galicia, aunque \u00e9ste a\u00fan por la v\u00eda convencional hasta que a partir del 10 de enero se reorganicen horarios y todos los trenes pasen por la via de alta velocidad. Un nutrido grupo de curiosos segu\u00edan desde la plataforma m\u00e1s cercana al edificio de viajeros, la marcha de este hist\u00f3rico servicio que se estren\u00f3 en el mismo and\u00e9n donde hace poco m\u00e1s de un mes la ministra de Fomento, Ana Pastor, llegaba en un tren de pruebas, un d\u00eda antes de que, por normativa electoral, estuviera prohibido cualquier acto inaugural o viaje de promoci\u00f3n pol\u00edtica de las infraestructuras.<\/p>\n<p>El viaje discurri\u00f3 perfecto, con toda comodidad, en poco m\u00e1s de hora y media. El tren realiz\u00f3 la primera parada en lo que ser\u00e1 la futura estaci\u00f3n de Medina del Campo (Valladolid), una breve detenci\u00f3n para poder hacer la transici\u00f3n del sistema de seguridad ASFA, que es el que inicialmente funciona el la l\u00ednea a Zamora, al m\u00e1s moderno ERTMS, vigente ya en la l\u00ednea m\u00e1s longeva desde Medina hacia Madrid. La segunda parada, la prevista en Segovia Guiomar, donde montaron un par de viajeros m\u00e1s.<\/p>\n<p>La llegada del convoy a Madrid Chamart\u00edn tuvo, como ocurriera en la estaci\u00f3n de Zamora a la salida, una amplia cobertura de los medios de comunicaci\u00f3n; incluso Televisi\u00f3n Espa\u00f1ola desplaz\u00f3 un equipo para hacerse eco del estreno. Habr\u00e1 que esperar un tiempo prudencial para ver si, ya con horarios definitivos y precios reales, sin promoci\u00f3n, la l\u00ednea de consolida.<\/p>\n<p><a href=\"http:\/\/www.laopiniondezamora.es\/zamora\/2015\/12\/18\/primer-tren-alta-velocidad-culmina\/892476.html\">La Opini\u00f3n de Zamora<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El tren Alvia que estren\u00f3 la alta velocidad ferroviaria en Zamora, con el primer servicio comercial que utilizaba la nueva l\u00ednea entre la capital y Olmedo, cubri\u00f3 el recorrido hasta la estaci\u00f3n madrile\u00f1a de Chamart\u00edn sin ning\u00fan tipo de problema, en un c\u00f3modo viaje que lleg\u00f3 incluso con dos minutos sobre el horario previsto. Fueron [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,2],"tags":[9644],"class_list":{"0":"post-35872","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-internacionales","7":"category-noticias","8":"tag-news"},"_links":{"self":[{"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/posts\/35872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/comments?post=35872"}],"version-history":[{"count":1,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/posts\/35872\/revisions"}],"predecessor-version":[{"id":35874,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/posts\/35872\/revisions\/35874"}],"wp:attachment":[{"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/media?parent=35872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/categories?post=35872"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/tags?post=35872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}