{"id":70973,"date":"2018-02-22T10:48:38","date_gmt":"2018-02-22T13:48:38","guid":{"rendered":"http:\/\/www.rieles.com\/front\/?p=70973"},"modified":"2018-02-22T10:49:39","modified_gmt":"2018-02-22T13:49:39","slug":"inicia-el-tendido-de-rieles-del-tren-jujuy-la-quiaca","status":"publish","type":"post","link":"https:\/\/www.rieles.com\/front\/inicia-el-tendido-de-rieles-del-tren-jujuy-la-quiaca\/","title":{"rendered":"Inicia el tendido de rieles del tren Jujuy \u2013 La Quiaca"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\">Jujuy, Argentina &#8211;<\/span> Con un acto que presidir\u00e1 el gobernador Morales, hoy a las 16 se pondr\u00e1 en marcha la colocaci\u00f3n de los primeros 7 kil\u00f3metros.<\/p>\n<p style=\"text-align: justify;\">Con la presencia del gobernador Gerardo Morales, se iniciar\u00e1n hoy, las obras de colocaci\u00f3n de las v\u00edas del tren Jujuy \u2013 La Quiaca, en el tramo entre Coiruro y el Arroyo Tumbaya Grande. En esta etapa, se prev\u00e9 la instalaci\u00f3n de 7 km de rieles en cuatro meses, siendo el objetivo final el tendido de 17 kil\u00f3metros hasta fin de a\u00f1o.<\/p>\n<p style=\"text-align: justify;\">El inicio de obra puede considerarse como un hecho trascendental para Jujuy, y se enmarca en el plan del Gobierno provincial de recuperar y poner en valor el tren en la provincia, proyecto que lleva adelante la Unidad Ejecutora. La vuelta del tren en la quebrada y la puna juje\u00f1a impactar\u00e1 positivamente en el desarrollo econ\u00f3mico de la regi\u00f3n en lo que respecta al turismo, la producci\u00f3n y el transporte de productos, teniendo adem\u00e1s como horizonte la instalaci\u00f3n de las zonas francas en La Quiaca y Perico.<\/p>\n<p style=\"text-align: justify;\">La actividad comenzar\u00e1 a las 16, con el recorrido del gobernador Gerardo Morales, por el sector de acopio de materiales, lugar donde se interiorizar\u00e1 del proceso de tallado de durmientes para su puesta a punto. Luego participar\u00e1, junto a un grupo de obreros, de la primera soldadura de rieles y ser\u00e1 parte del proceso central de fundici\u00f3n del material y colocaci\u00f3n final de las primeras v\u00edas.<\/p>\n<p style=\"text-align: justify;\"><strong>Especificaciones del trabajo<\/strong><\/p>\n<p style=\"text-align: justify;\">Para la colocaci\u00f3n de v\u00edas se requiere un trabajo arduo de preparaci\u00f3n previo del terreno que involucra diferentes actividades como: el entallado de durmientes para igualar tama\u00f1os, la selecci\u00f3n de rieles, la preparaci\u00f3n del terrapl\u00e9n donde seguidamente se colocar\u00e1 la malla geotextil a modo de aislante, la piedra balasto especialmente preparada para la obra que debe cubrir la extensi\u00f3n del terrapl\u00e9n, la colocaci\u00f3n de durmientes y finalmente la soldadura y colocaci\u00f3n de rieles.<\/p>\n<p style=\"text-align: justify;\">En base a los estudios previos realizados en relaci\u00f3n al material rodante, el clima y la capacidad portante se defini\u00f3 la colocaci\u00f3n de tramos de rieles de 36 metros, unidos con una junta de eclisas abulonadas. Dicho esquema se consider\u00f3 el \u00f3ptimo para resistir la contracci\u00f3n y dilataci\u00f3n del material por las diferencias de temperaturas.<\/p>\n<p style=\"text-align: justify;\">As\u00ed mismo, se defini\u00f3 que tipo de piedra balasto sea la piedra partida, mientras que la cantidad de durmientes por tramo estimados ser\u00e1n entre 1700 a 1760 por km, lo que garantizar\u00e1 una capacidad portante de 18 toneladas por eje aproximadamente.<\/p>\n<p style=\"text-align: justify;\">En la misma l\u00ednea, se seleccion\u00f3 el material a usar como rieles, durmientes adecuados, accesorios como bulones y eclisas; previendo adem\u00e1s la compra de nuevo material seg\u00fan la necesidad de la obra.<\/p>\n<p style=\"text-align: justify;\"><strong>Sobre el proyecto<\/strong><\/p>\n<p style=\"text-align: justify;\">La reactivaci\u00f3n del ramal se est\u00e1 realizando en base a su dise\u00f1o original, debiendo modificarse en algunos puntos por la variaci\u00f3n misma del paisaje, intrusiones y r\u00edos.<\/p>\n<p style=\"text-align: justify;\">Asimismo, se contin\u00faa trabajando sobre las futuras estaciones, las tareas log\u00edsticas, adaptando tecnolog\u00eda y dem\u00e1s actividades que dicha obra de gran envergadura requiere, con el claro objetivo de lograr tener dos formaciones funcionando a partir de junio de 2019, que recorran las v\u00edas como servicio tur\u00edstico.<\/p>\n<p>&nbsp;<\/p>\n<p>Fuente y fotograf\u00eda: <a href=\"http:\/\/www.jujuyonlinenoticias.com.ar\/jujuy\/2018\/2\/22\/inicia-tendido-rieles-tren-jujuy-quiaca-49423.html\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff0000;\"><strong>jujuyonlinenoticias<\/strong><\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jujuy, Argentina &#8211; Con un acto que presidir\u00e1 el gobernador Morales, hoy a las 16 se pondr\u00e1 en marcha la colocaci\u00f3n de los primeros 7 kil\u00f3metros. Con la presencia del gobernador Gerardo Morales, se iniciar\u00e1n hoy, las obras de colocaci\u00f3n de las v\u00edas del tren Jujuy \u2013 La Quiaca, en el tramo entre Coiruro y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":70974,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[9644],"class_list":{"0":"post-70973","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nacionales","8":"tag-news"},"_links":{"self":[{"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/posts\/70973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/comments?post=70973"}],"version-history":[{"count":2,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/posts\/70973\/revisions"}],"predecessor-version":[{"id":70976,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/posts\/70973\/revisions\/70976"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/media\/70974"}],"wp:attachment":[{"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/media?parent=70973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/categories?post=70973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/tags?post=70973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}