{"id":70984,"date":"2018-02-22T09:35:14","date_gmt":"2018-02-22T12:35:14","guid":{"rendered":"http:\/\/www.rieles.com\/front\/?p=70984"},"modified":"2018-02-22T11:06:31","modified_gmt":"2018-02-22T14:06:31","slug":"bolivia-fija-para-marzo-reunion-de-ministros-de-obras-publicas-y-transporte-para-el-tren-bioceanico","status":"publish","type":"post","link":"https:\/\/www.rieles.com\/front\/bolivia-fija-para-marzo-reunion-de-ministros-de-obras-publicas-y-transporte-para-el-tren-bioceanico\/","title":{"rendered":"Bolivia fija para marzo reuni\u00f3n de ministros de Obras P\u00fablicas y Transporte para el tren bioce\u00e1nico"},"content":{"rendered":"<p style=\"text-align: justify;\">La Secretaria T\u00e9cnica del tren bioce\u00e1nico debe encargarse de realizar el estudio a dise\u00f1o final de la megaobra, consolidar acuerdos con universidades locales y extranjeras, y concretar las sociedades p\u00fablico privadas para el financiamiento<\/p>\n<p style=\"text-align: justify;\">El ministro de Obras P\u00fablicas, Servicios y Vivienda, Milton Claros, inform\u00f3 este mi\u00e9rcoles que se prepara una reuni\u00f3n con los ministros de Obras P\u00fablicas de pa\u00edses vecinos involucrados en el proyecto del tren bioce\u00e1nico, para aprobar la propuesta boliviana sobre el funcionamiento de la secretaria t\u00e9cnica para esa obra.<\/p>\n<p style=\"text-align: justify;\">La autoridad dijo que se enviaron notas a sus pares y se aguarda la respuesta correspondiente para consolidar esa reuni\u00f3n, prevista para el \u00ab16 de marzo en la ciudad de Cochabamba\u00bb.<\/p>\n<p style=\"text-align: justify;\">\u00abHemos mandado notas el d\u00eda de ayer y hoy para el tema de una reuni\u00f3n en marzo, eso es lo que estamos viendo, una reuni\u00f3n en Cochabamba, para consolidar, confirmar y aprobar todo este tema\u00bb, indic\u00f3 a los periodistas en Palacio de Gobierno.<\/p>\n<p style=\"text-align: justify;\">La Secretaria T\u00e9cnica del tren bioce\u00e1nico debe encargarse de realizar el estudio a dise\u00f1o final de esa megaobra, consolidar acuerdos con universidades locales y extranjeras, y concretar las sociedades p\u00fablico privadas para el financiamiento del proyecto, de acuerdo con informaci\u00f3n del Ministerio de Obras P\u00fablicas.<\/p>\n<p style=\"text-align: justify;\">A la fecha, el proyecto del tren bioce\u00e1nico tiene un estudio de preinversi\u00f3n elaborado por Bolivia y dividido en cuatro ejes: el primero de prospectiva comercial, mercado y alternativas log\u00edsticas; el segundo estrat\u00e9gico y corredor resultante; el tercero de evaluaci\u00f3n ambiental estrat\u00e9gica; y el cuarto complementario de alternativas de trazo, trazado, alineamiento definitivo, dise\u00f1o b\u00e1sico preliminar, costos de construcci\u00f3n y operaci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>Fuente y fotograf\u00eda: <a href=\"http:\/\/www.la-razon.com\/economia\/Bioceanico-Bolivia-Obras-Publicas-Transporte_0_2879112087.html\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff0000;\"><strong>la-razon<\/strong><\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Secretaria T\u00e9cnica del tren bioce\u00e1nico debe encargarse de realizar el estudio a dise\u00f1o final de la megaobra, consolidar acuerdos con universidades locales y extranjeras, y concretar las sociedades p\u00fablico privadas para el financiamiento El ministro de Obras P\u00fablicas, Servicios y Vivienda, Milton Claros, inform\u00f3 este mi\u00e9rcoles que se prepara una reuni\u00f3n con los ministros [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":70985,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[9644],"class_list":{"0":"post-70984","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-internacionales","8":"tag-news"},"_links":{"self":[{"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/posts\/70984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/comments?post=70984"}],"version-history":[{"count":1,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/posts\/70984\/revisions"}],"predecessor-version":[{"id":70986,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/posts\/70984\/revisions\/70986"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/media\/70985"}],"wp:attachment":[{"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/media?parent=70984"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/categories?post=70984"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/tags?post=70984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}