{"id":77902,"date":"2018-08-02T11:45:52","date_gmt":"2018-08-02T14:45:52","guid":{"rendered":"http:\/\/www.rieles.com\/front\/?p=77902"},"modified":"2018-08-02T14:39:56","modified_gmt":"2018-08-02T17:39:56","slug":"puede-volver-el-tren-de-pasajeros-a-la-region","status":"publish","type":"post","link":"https:\/\/www.rieles.com\/front\/puede-volver-el-tren-de-pasajeros-a-la-region\/","title":{"rendered":"\u00bfPuede volver el tren de pasajeros a la regi\u00f3n?"},"content":{"rendered":"<p style=\"text-align: justify;\">El Foro Permanente en Defensa del Derecho Ferroviario tiene un proyecto con un presupuesto estimativo de lo que costar\u00eda reactivar los ramales Rosario-Casilda y Rosario-Ca\u00f1ada de G\u00f3mez<\/p>\n<p style=\"text-align: justify;\">Legisladores de distintas localidades del sur santafesino, autoridades de municipios y comunas, m\u00e1s asociaciones ferroviarias, siguen insistiendo con reavivar un medio de transporte que se perdi\u00f3 con el paso del tiempo. De hecho, ya existe un costo estimativo de cuanto saldr\u00eda poner nuevamente en funcionamiento dos de los principales ramales que confluyen en Rosario.<\/p>\n<p style=\"text-align: justify;\">Durante el 2017 se cre\u00f3 en Foro Permanente en Defensa del Derecho Ferroviario. Este grupo que surgi\u00f3 de una audiencia p\u00fablica donde hubo m\u00e1s de cuarenta expositores, tom\u00f3 la causa como propia y se re\u00fane peri\u00f3dicamente, como lo hizo el pasado martes en Ca\u00f1ada de G\u00f3mez.<\/p>\n<p style=\"text-align: justify;\">Seg\u00fan el concejal rosarino, Eduardo Tonioli, integrante del foro, hay estudios t\u00e9cnicos hechos por la Provincia de Santa Fe desde la Unidad de Gesti\u00f3n Ferroviaria. En ese sentido, se arroj\u00f3 que necesitar\u00edan unos 80 millones de d\u00f3lares para recuperar los ramales: Rosario-Casilda y Rosario-Ca\u00f1ada. \u00abEl inconveniente m\u00e1s grande es que esta situaci\u00f3n incluye al interior del pa\u00eds\u00bb, adujo el edil en los micr\u00f3fonos de Radio Casilda.<\/p>\n<p style=\"text-align: justify;\">Seg\u00fan lo ve Tonioli, no es una gran inversi\u00f3n si existe el apoyo de la Naci\u00f3n. Aunque por el momento, el ministro Guillermo Dietrich, titular de la cartera de Transporte, no estar\u00eda dispuestos a recibirlos en su despacho. El proyecto incluye reparaciones y refacciones de v\u00edas, m\u00e1s el material rodante.<\/p>\n<p style=\"text-align: justify;\">La necesidad de sumar una alternativa al transporte automotor parece imponerse en la regi\u00f3n. Adem\u00e1s que resultar\u00eda m\u00e1s econ\u00f3mico para el bolsillo del pasaje y, posiblemente, m\u00e1s veloz y seguro.<\/p>\n<p style=\"text-align: justify;\">El Foro en Defensa del Derecho Ferroviario volver\u00e1 a reunirse pronto en la localidad de P\u00e9rez, otro punto que consideran neur\u00e1lgico para darle fuerza a proyecto.<\/p>\n<p>Audio\u00a0<span style=\"color: #ff0000;\"><a title=\"Eduardo Tonioli, concejal de Rosario\" href=\"https:\/\/radiocut.fm\/audiocut\/eduardo-tonioli-concejal-de-rosario\/\" target=\"_blank\" rel=\"noopener\">Eduardo Tonioli, concejal de Rosario<\/a><\/span><\/p>\n<p>Fuente y fotograf\u00eda:\u00a0<a href=\"http:\/\/www.casildaplus.com\/ennoticias\/Puede-volver-el-tren-de-pasajeros-a-la-region-20180801-0010.html\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff0000;\"><strong>casildaplus<\/strong><\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Foro Permanente en Defensa del Derecho Ferroviario tiene un proyecto con un presupuesto estimativo de lo que costar\u00eda reactivar los ramales Rosario-Casilda y Rosario-Ca\u00f1ada de G\u00f3mez Legisladores de distintas localidades del sur santafesino, autoridades de municipios y comunas, m\u00e1s asociaciones ferroviarias, siguen insistiendo con reavivar un medio de transporte que se perdi\u00f3 con el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":77903,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[9644],"class_list":["post-77902","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacionales","tag-news"],"_links":{"self":[{"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/posts\/77902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/comments?post=77902"}],"version-history":[{"count":1,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/posts\/77902\/revisions"}],"predecessor-version":[{"id":77907,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/posts\/77902\/revisions\/77907"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/media\/77903"}],"wp:attachment":[{"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/media?parent=77902"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/categories?post=77902"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/tags?post=77902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}