{"id":92020,"date":"2019-09-12T09:09:54","date_gmt":"2019-09-12T12:09:54","guid":{"rendered":"http:\/\/www.rieles.com\/front\/?p=92020"},"modified":"2019-09-12T09:09:54","modified_gmt":"2019-09-12T12:09:54","slug":"gran-fiesta-para-homenajear-a-los-inmigrantes-en-la-explanada-del-ferrocarril","status":"publish","type":"post","link":"https:\/\/www.rieles.com\/front\/gran-fiesta-para-homenajear-a-los-inmigrantes-en-la-explanada-del-ferrocarril\/","title":{"rendered":"Gran fiesta para homenajear a los inmigrantes en la explanada del Ferrocarril"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Mendoza &#8211; Argentina &#8211; 12\/09\/2019:\u00a0<\/strong>Durante la temporada de verano San Rafael tuvo en el parque Yrigoyen su exitosa Feria de las Culturas, con la participaci\u00f3n de diferentes colectividades y una gran aceptaci\u00f3n del p\u00fablico.<\/p>\n<p style=\"text-align: justify;\">Luego de esa exitosa experiencia, este s\u00e1bado se reeditar\u00e1 la actividad pero con la \u201cexcusa\u201d de la fiesta del D\u00eda del Inmigrante, que se realizar\u00e1 en la explanada del Ferrocarril desde las 18 hasta la medianoche con entrada libre y gratuita.<\/p>\n<p style=\"text-align: justify;\">La propuesta impulsada desde el Padr\u00f3n de Extranjeros ser\u00e1 similar a la \u201cmovida\u201d realizada durante la temporada veraniega e incluir\u00e1 propuestas para toda la familia.<\/p>\n<p style=\"text-align: justify;\">Dentro del cronograma de actividades estar\u00e1 \u201cla participaci\u00f3n de la Feria Verde del INTA, tambi\u00e9n se realizar\u00e1n patios de comidas, las presentaciones de las colectividades, patio de artesanos y shows en vivo para que disfrute toda la familia\u201d.<\/p>\n<p style=\"text-align: justify;\">El D\u00eda del inmigrante en la Argentina se celebra el 4 de septiembre de cada a\u00f1o desde que se lo estableci\u00f3 mediante el Decreto N\u00ba 21.430 del a\u00f1o 1949, siendo presidente Juan Domingo Per\u00f3n. Se eligi\u00f3 esa fecha para recordar la llegada de los inmigrantes al pa\u00eds luego de la disposici\u00f3n dictada por el Primer Triunvirato en esa fecha de 1812, que ofreciera \u201csu inmediata protecci\u00f3n a los individuos de todas las naciones y a sus familias que deseen fijar su domicilio en el territorio\u201d.<\/p>\n<p><strong>Fuente:\u00a0<a href=\"https:\/\/diariosanrafael.com.ar\/gran-fiesta-para-homenajear-a-los-inmigrantes-en-la-explanada-del-ferrocarril-194515\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff0000;\">Diario de San Rafael<\/span><\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mendoza &#8211; Argentina &#8211; 12\/09\/2019:\u00a0Durante la temporada de verano San Rafael tuvo en el parque Yrigoyen su exitosa Feria de las Culturas, con la participaci\u00f3n de diferentes colectividades y una gran aceptaci\u00f3n del p\u00fablico. Luego de esa exitosa experiencia, este s\u00e1bado se reeditar\u00e1 la actividad pero con la \u201cexcusa\u201d de la fiesta del D\u00eda del [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":92021,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[9105,9644],"class_list":["post-92020","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacionales","tag-actualidad","tag-news"],"_links":{"self":[{"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/posts\/92020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/comments?post=92020"}],"version-history":[{"count":1,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/posts\/92020\/revisions"}],"predecessor-version":[{"id":92022,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/posts\/92020\/revisions\/92022"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/media\/92021"}],"wp:attachment":[{"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/media?parent=92020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/categories?post=92020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/tags?post=92020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}