{"id":99712,"date":"2020-10-09T12:25:59","date_gmt":"2020-10-09T15:25:59","guid":{"rendered":"http:\/\/www.rieles.com\/front\/?p=99712"},"modified":"2020-10-09T12:25:59","modified_gmt":"2020-10-09T15:25:59","slug":"un-proyecto-mendocino-busca-que-el-tren-vuelva-a-pasar-por-la-difunta-correa","status":"publish","type":"post","link":"https:\/\/www.rieles.com\/front\/un-proyecto-mendocino-busca-que-el-tren-vuelva-a-pasar-por-la-difunta-correa\/","title":{"rendered":"Un proyecto mendocino busca que el tren vuelva a pasar por la Difunta Correa"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>San Juan &#8211; Argentina &#8211; 09\/10\/2020:\u00a0<\/strong>El extinto recorrido del tren Belgrano que pasara alguna vez por Caucete hacia la Difunta Correa y hasta Mendoza podr\u00eda ser un realidad si todos los pron\u00f3sticos salen bien, por lo menos una parte de este tramo que vemos derruido pro le paso del tiempo en nuestro camino hacia el paraje de Vallecito.<\/p>\n<p style=\"text-align: justify;\">El pasado d\u00eda 29 de septiembre , durante la Sesi\u00f3n Ordinaria del Concejo Deliberante del departamento Lavalle, en Mendoza dio por aprobado el Proyecto de Declaraci\u00f3n que tiene como finalidad declarar de Inter\u00e9s Departamental el Proyecto denominado \u201cTren de Las Arenas\u201d y nuevas estaciones del Ferrocarril Belgrano, impulsado por la Municipalidad de Lavalle, que tiene como objetivo recuperar y poner en funcionamiento el Ramal A10 del Ferrocarril Belgrano.<\/p>\n<p style=\"text-align: justify;\">El proyecto denominado \u201cTren de las Arenas\u201d tiene por objetivo la recuperaci\u00f3n y puesta en funcionamiento del Ramal A10 del FFCC General Belgrano.<\/p>\n<p style=\"text-align: justify;\">En primera instancia se busca poner en marcha el tramo comprendido entre las localidades de Costa de Araujo y Lagunas del Rosario, con una extensi\u00f3n de 80 km, informo Despertador Lavalle, portal de noticias de esa localidad.<\/p>\n<p style=\"text-align: justify;\">Lo que se pretende lograr con este proyecto es la reactivaci\u00f3n del sistema ferroviario, atendiendo tres aspectos fundamentales como lo son: el transporte de pasajeros, el turismo y la operaci\u00f3n de cargas.<\/p>\n<p style=\"text-align: justify;\">Estos semblantes resultan estrat\u00e9gicos para el desarrollo tanto del Departamento de Lavalle como de la regi\u00f3n.<\/p>\n<p style=\"text-align: justify;\">En esta l\u00ednea de ideas, se tiene la intenci\u00f3n que el proyecto se desarrolle en dos etapas: la primera de ellas dentro de la Provincia de Mendoza (uniendo las localidades de Costa de Araujo y Lagunas del Rosario, proyectando en su traza dos estaciones intermedias, una de ellas en El Alpero y la otra en San Jos\u00e9) y en la segunda en la Provincia de San Juan, incluyendo en el recorrido al paraje Difunta Correa, ubicado en el Departamento de Caucete, reconocido como de visita de promesantes y turistas.<\/p>\n<p style=\"text-align: justify;\">La zona tiene un gran potencial tur\u00edstico por su historia y valor, rescatando la cultura originaria del pueblo lavallino.<\/p>\n<p style=\"text-align: justify;\">El Ejecutivo de la Municipalidad de Lavalle ha iniciado las gestiones ante el Ministerio de Transporte de la Naci\u00f3n con la finalidad de obtener autorizaci\u00f3n y acompa\u00f1amiento para construir tramos de v\u00edas para desv\u00edos de trenes, reparaciones y\/o estacionamiento, como as\u00ed tambi\u00e9n para poner en valor estaciones existentes y la construcci\u00f3n de nuevas estaciones e infraestructura ubicadas estrat\u00e9gicamente para el funcionamiento planificado.<\/p>\n<p><strong>Fuente:\u00a0<a href=\"https:\/\/www.infocaucete.com.ar\/comunidad\/08\/10\/2020\/un-proyecto-mendocino-busca-que-el-tren-vuelva-a-pasar-por-la-difunta-correa\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff0000;\">Info Caucete<\/span><\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>San Juan &#8211; Argentina &#8211; 09\/10\/2020:\u00a0El extinto recorrido del tren Belgrano que pasara alguna vez por Caucete hacia la Difunta Correa y hasta Mendoza podr\u00eda ser un realidad si todos los pron\u00f3sticos salen bien, por lo menos una parte de este tramo que vemos derruido pro le paso del tiempo en nuestro camino hacia el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":99713,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[10855,9105,9644],"class_list":["post-99712","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacionales","tag-10855","tag-actualidad","tag-news"],"_links":{"self":[{"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/posts\/99712","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/comments?post=99712"}],"version-history":[{"count":1,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/posts\/99712\/revisions"}],"predecessor-version":[{"id":99714,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/posts\/99712\/revisions\/99714"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/media\/99713"}],"wp:attachment":[{"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/media?parent=99712"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/categories?post=99712"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rieles.com\/front\/wp-json\/wp\/v2\/tags?post=99712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}